{"id":509642,"date":"2025-07-16T15:48:22","date_gmt":"2025-07-16T13:48:22","guid":{"rendered":"https:\/\/medandbeauty.com\/product\/pantaloni-medici-da-donna-flare-scrubs-basic-kiwi\/"},"modified":"2026-07-13T15:10:37","modified_gmt":"2026-07-13T13:10:37","slug":"pantaloni-medici-da-donna-flare-scrubs-basic-kiwi","status":"publish","type":"product","link":"https:\/\/medandbeauty.com\/it\/product\/pantaloni-medici-da-donna-flare-scrubs-basic-kiwi\/","title":{"rendered":"Pantaloni medici da donna FLARE scrubs Basic KIWI"},"content":{"rendered":"<p>Ora sono disponibili i nostri <strong>pantaloni da medico<\/strong> pi\u00f9 venduti <strong>con il taglio svasato FLARE!<\/strong><\/p>\n<p><span style=\"color: #000000;\">Se desideri indumenti medici realizzati con i migliori materiali di qualit\u00e0 per il massimo comfort, i nostri pantaloni medici<strong> <\/strong> <\/span><strong><span style=\"color: #000000;\">Pantaloni medici Flare Basic nel colore Kiwi<\/span><\/strong><span style=\"color: #000000;\"> sono un must del tuo guardaroba.<\/span><\/p>\n<p style=\"color: #000000;\"><strong>I pantaloni medici da donna Flare scrubs Basic Kiwi <\/strong>sono stati realizzati con un tessuto morbido al tatto ed estremamente piacevole da indossare, che garantisce il massimo comfort nell&#8217;indossarli e il mantenimento di una gamma completa di movimenti.<\/p>\n<p style=\"color: #000000;\">La combinazione di poliestere, viscosa e lycra rende il tessuto perfettamente adatto alla figura femminile, oltre ad essere estremamente resistente e molto traspirante.<\/p>\n<p><span style=\"color: #000000;\">Il comfort al 100% \u00e8 garantito dalla vita leggermente alta e dall&#8217;ampia fascia elastica con coulisse per una facile regolazione della taglia.<\/span><strong style=\"color: #000000;\">. <\/strong><strong><span style=\"color: #000000;\">I pantaloni medici svasati di Med &#038; Beauty<\/span><\/strong><span style=\"color: #000000;\"> non limitano i movimenti, anche se indossati in modo prolungato.<\/span><\/p>\n<p style=\"color: #000000;\">I <strong>pantaloni medici Flare in colore Kiwi <\/strong>si abbinano bene a qualsiasi abbigliamento e le quattro tasche spaziose e pratiche ti permetteranno di tenere a portata di mano tutti i tuoi oggetti e strumenti di lavoro.<\/p>\n<p><span style=\"color: #000000;\">Componi il tuo set da sogno <\/span><strong style=\"color: #000000;\">di abbigliamento medico<\/strong><span style=\"color: #000000;\">abbinando i pantaloni da medico Flare Kiwi a<\/span><strong><span style=\"color: #000000;\"> pantaloni medici da donna Flare Kiwi con due tasche, camicetta medica con una tasca <\/span><\/strong><span style=\"color: #000000;\">o la nostra novit\u00e0, la camicetta medica <\/span><strong><span style=\"color: #000000;\">camicetta medica Flex<\/span><\/strong><span style=\"color: #000000;\"> realizzata con lo stesso materiale.<\/span><\/p>\n<p style=\"color: #000000;\">Mescolate liberamente i colori e create look unici o optate per un classico e intramontabile look monocolore.<\/p>\n<ul style=\"color: #000000;\">\n<li>Vita elastica con coulisse<\/li>\n<li><span style=\"font-family: inherit;\">4 tasche pratiche e capienti<\/span><\/li>\n<li><span style=\"font-family: inherit;\">Gambe svasate<\/span><\/li>\n<li><span style=\"font-family: inherit;\">Vita alta per enfatizzare la figura<\/span><\/li>\n<\/ul>\n<p style=\"color: #000000;\"><strong> <\/strong><\/p>\n<p style=\"color: #000000;\">\nI<strong>nformazioni aggiuntive:<\/strong> Le modelle nelle foto indossano la taglia S e sono alte 170-174 cm.<\/p>\n<p style=\"color: #000000;\">Se vi state chiedendo quale taglia scegliere, date un&#8217;occhiata alla tabella delle taglie. In caso di dubbi, inviateci le vostre misure e noi le adatteremo per voi. <\/p>\n<p style=\"color: #000000;\">I colori dei capi della<a href=\"https:\/\/medandbeauty.com\/it\/shop\/per-lei\/collezione-basic-per-lei\/\" target=\"_blank\" rel=\"noopener\"> collezione Basic<\/a> non corrispondono a quelli della <a href=\"https:\/\/medandbeauty.com\/it\/shop\/per-lei\/collezione-premium-per-lei\/\" target=\"_blank\" rel=\"noopener\">collezione Premium<\/a>, poich\u00e9 sono realizzati con tessuti diversi.<\/p>\n<p style=\"color: #000000;\">Le tonalit\u00e0 dei singoli capi nelle immagini possono differire da quelle reali, a causa della variet\u00e0 di apparecchiature elettroniche disponibili e delle loro impostazioni individuali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ora sono disponibili i nostri pantaloni da medico pi\u00f9 venduti con il taglio svasato FLARE! Se desideri indumenti medici realizzati con i migliori materiali di qualit\u00e0 per il massimo comfort, i nostri pantaloni medici Pantaloni medici Flare Basic nel colore Kiwi sono un must del tuo guardaroba. I pantaloni medici da donna Flare scrubs Basic [&hellip;]<\/p>\n","protected":false},"featured_media":469367,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"kolor":[595],"rodzaj-ubrania":[572,556],"ubranie":[1501],"product_brand":[],"product_cat":[2225],"product_tag":[],"class_list":["post-509642","product","type-product","status-publish","has-post-thumbnail","kolor-verdi","rodzaj-ubrania-pantaloni-medici","rodzaj-ubrania-camici","ubranie-pantaloni-medici-da-donna-scrub-basic-con-risvolto","product_cat-saldi-estivi","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/product\/509642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/comments?post=509642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/media\/469367"}],"wp:attachment":[{"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/media?parent=509642"}],"wp:term":[{"taxonomy":"kolor","embeddable":true,"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/kolor?post=509642"},{"taxonomy":"rodzaj-ubrania","embeddable":true,"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/rodzaj-ubrania?post=509642"},{"taxonomy":"ubranie","embeddable":true,"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/ubranie?post=509642"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/product_brand?post=509642"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/product_cat?post=509642"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/medandbeauty.com\/it\/wp-json\/wp\/v2\/product_tag?post=509642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}